{"id":395,"date":"2024-07-17T14:31:16","date_gmt":"2024-07-17T12:31:16","guid":{"rendered":"https:\/\/www.casarufo.com\/menus\/"},"modified":"2025-05-01T17:48:39","modified_gmt":"2025-05-01T15:48:39","slug":"menus","status":"publish","type":"page","link":"https:\/\/www.casarufo.com\/en\/menus\/","title":{"rendered":"Menus"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row el_class=&#8221;menu_interior&#8221;][vc_column][vc_column_text]<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"https:\/\/www.casarufo.com\/en\/a_la_carte\/\">\u00c0 la Carte<\/a><\/li>\n<li><strong><a href=\"https:\/\/www.casarufo.com\/en\/menus\/\">Menus<\/a><\/strong><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721213336016{background-color: #1c2623 !important;}&#8221; el_class=&#8221;cab_menus&#8221;][vc_column][vc_column_text]<\/p>\n<h2>The Restaurant<\/h2>\n<h1>MENU I<\/h1>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<ul>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_huevo.png\" alt=\"\" width=\"20\" height=\"18\" \/> Egg<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-153 size-full\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_gluten.png\" alt=\"\" width=\"18\" height=\"18\" \/> Gluten<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-156 size-full\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_pescado.png\" alt=\"\" width=\"22\" height=\"15\" \/>Fish<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-155 size-full\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_lactosa.png\" alt=\"\" width=\"16\" height=\"17\" \/> Lactose<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<h3>APPETIZERS<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Egg croquettes<\/strong> (Homemade)<\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_huevo.png\" alt=\"\" width=\"20\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-153\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_gluten.png\" alt=\"\" width=\"18\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-155\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_lactosa.png\" alt=\"\" width=\"16\" height=\"17\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Smoked salmon<\/strong>(traditionally smoked in-house)<\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_pescado.png\" alt=\"\" width=\"20\" height=\"18\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Navarre asparagus<\/strong> (with extra virgin olive oil)<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721220332805{padding-top: 70px !important;background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<h3>MAIN<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Grilled T-bone steak<br \/>\n<\/strong>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-153\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_gluten.png\" alt=\"\" width=\"18\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_pescado.png\" alt=\"\" width=\"20\" height=\"18\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721220332805{padding-top: 70px !important;background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<h3>DESSERTS<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Tolosa almond wafers and rolled pastries with truffles\u00a0<\/strong><\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-153\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_gluten.png\" alt=\"\" width=\"18\" height=\"18\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721220737303{background-color: #1c2623 !important;}&#8221; el_class=&#8221;precio_por_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Price per person: \u20ac68<\/strong> (10% VAT included)<br \/>\n(Crianza wine, water, and coffee)<\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<\/p>\n<h2><\/h2>\n<h2 style=\"text-align: center;\"><strong>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/strong><\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721213336016{background-color: #1c2623 !important;}&#8221; el_class=&#8221;cab_menus&#8221;][vc_column][vc_column_text]<\/p>\n<h2>The Restaurant<\/h2>\n<h1>MENU II<\/h1>\n<p>[\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<ul>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_huevo.png\" alt=\"\" width=\"20\" height=\"18\" \/> Egg<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-153 size-full\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_gluten.png\" alt=\"\" width=\"18\" height=\"18\" \/> Gluten<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-156 size-full\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_pescado.png\" alt=\"\" width=\"22\" height=\"15\" \/>Fish<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-155 size-full\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_lactosa.png\" alt=\"\" width=\"16\" height=\"17\" \/> Lactose<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<h3>APPETIZERS<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Egg croquettes (<\/strong>Homemade<strong>)<\/strong><\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_huevo.png\" alt=\"\" width=\"20\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-153\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_gluten.png\" alt=\"\" width=\"18\" height=\"18\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-155\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_lactosa.png\" alt=\"\" width=\"16\" height=\"17\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Smoked salmon<\/strong>(traditionally smoked in-house)<\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_pescado.png\" alt=\"\" width=\"20\" height=\"18\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Foie Mi-cuit<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Smoked duck breast<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721220332805{padding-top: 70px !important;background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<h3>MAIN<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Cod<\/strong><\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-154\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_pescado.png\" alt=\"\" width=\"20\" height=\"18\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Grilled T-bone steak<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721220332805{padding-top: 70px !important;background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text]<\/p>\n<h3>DESSERTS<\/h3>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Tolosa almond wafers and rolled pastries with truffles\u00a0<\/strong><\/p>\n<p>[\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-153\" src=\"https:\/\/www.casarufo.com\/wp-content\/uploads\/2024\/07\/icon_gluten.png\" alt=\"\" width=\"18\" height=\"18\" \/>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721220737303{background-color: #1c2623 !important;}&#8221; el_class=&#8221;precio_por_menu&#8221;][vc_column][vc_column_text]<\/p>\n<p style=\"text-align: center;\"><strong>Price per person: \u20ac76 (10% VAT included)<\/strong><\/p>\n<p style=\"text-align: center;\">(Crianza wine, water, and coffee)<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721218207280{margin-bottom: 200px !important;padding-bottom: 60px !important;background-color: #1c2623 !important;}&#8221;][vc_column][vc_btn title=&#8221;RESERVE A TABLE&#8221; align=&#8221;center&#8221; el_class=&#8221;boton_transparente&#8221; link=&#8221;url:https%3A%2F%2Fwww.casarufo.com%2Fen%2Freservas%2F&#8221;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row el_class=&#8221;menu_interior&#8221;][vc_column][vc_column_text] \u00c0 la Carte Menus &nbsp; [\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721213336016{background-color: #1c2623 !important;}&#8221; el_class=&#8221;cab_menus&#8221;][vc_column][vc_column_text] The Restaurant MENU I [\/vc_column_text][vc_row_inner][vc_column_inner][vc_column_text] Egg Gluten Fish Lactose [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text] APPETIZERS [\/vc_column_text][vc_column_text] Egg croquettes (Homemade) [\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;][\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text] Smoked salmon(traditionally smoked in-house) [\/vc_column_text][vc_column_text el_class=&#8221;menu_iconos&#8221;][\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1721219740375{background-color: #1c2623 !important;}&#8221; el_class=&#8221;fila_menu&#8221;][vc_column][vc_column_text] Navarre asparagus (with extra virgin olive oil) [\/vc_column_text][\/vc_column][\/vc_row][vc_row [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-395","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/pages\/395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/comments?post=395"}],"version-history":[{"count":11,"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/pages\/395\/revisions"}],"predecessor-version":[{"id":940,"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/pages\/395\/revisions\/940"}],"wp:attachment":[{"href":"https:\/\/www.casarufo.com\/en\/wp-json\/wp\/v2\/media?parent=395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}